{"id":58,"date":"2017-06-07T20:44:00","date_gmt":"2017-06-07T20:44:00","guid":{"rendered":"https:\/\/carelli.se\/?page_id=58"},"modified":"2026-04-17T18:36:00","modified_gmt":"2026-04-17T18:36:00","slug":"byt-assistansbolag","status":"publish","type":"page","link":"https:\/\/carelli.se\/es\/personligassistans\/byt-assistansbolag\/","title":{"rendered":"Elija su empresa de asistencia"},"content":{"rendered":"<div id=\"cs-content\" class=\"cs-content\"><div class=\"x-section e58-e1 m1m-0 m1m-1\" id=\"start\"><div class=\"x-row x-container max width e58-e2 m1m-6 m1m-7 m1m-9\"><div class=\"x-row-inner\"><div class=\"x-col e58-e3 m1m-b m1m-c\"><div class=\"x-text x-text-headline e58-e4 m1m-f m1m-g m1m-h m1m-3 x-effect-exit\" data-x-effect=\"{&quot;scroll&quot;:true,&quot;offsetTop&quot;:&quot;10%&quot;,&quot;offsetBottom&quot;:&quot;10%&quot;,&quot;behaviorScroll&quot;:&quot;fire-once&quot;}\"><div class=\"x-text-content\"><div class=\"x-text-content-text\"><h1 class=\"x-text-content-text-primary\">C\u00f3mo elegir o cambiar\nempresa de asistencia<\/h1>\n<\/div><\/div><\/div><div class=\"x-text x-text-headline e58-e5 m1m-f m1m-g m1m-i m1m-3 m1m-4 x-effect-exit\" data-x-effect=\"{&quot;scroll&quot;:true,&quot;offsetTop&quot;:&quot;10%&quot;,&quot;offsetBottom&quot;:&quot;10%&quot;,&quot;behaviorScroll&quot;:&quot;fire-once&quot;}\"><div class=\"x-text-content\"><div class=\"x-text-content-text\"><h4 class=\"x-text-content-text-primary\">\u00bfRecibe actualmente asistencia personal pero est\u00e1 pensando en cambiar de proveedor de asistencia? \u00bfO es la primera vez que busca un proveedor de asistencia? Elegir una empresa de asistencia es un gran paso y algo que se percibe como complicado. Le ayudaremos a empezar con nosotros y a que la transici\u00f3n sea fluida.<\/h4>\n<\/div><\/div><\/div><\/div><div class=\"x-col e58-e6 m1m-b\"><div class=\"x-acc e58-e7 m1m-l m1m-m\" id=\"x-acc-e58-e7\"><div class=\"e58-e8 x-acc-item\"><button id=\"tab-e58-e8\" class=\"x-acc-header\" role=\"button\" aria-expanded=\"false\" aria-controls=\"panel-e58-e8\" data-x-toggle=\"collapse\" data-x-toggleable=\"e58-e8\" type=\"button\"><span class=\"x-acc-header-content\"><span class=\"x-acc-header-indicator\"><i class=\"x-icon\" aria-hidden=\"true\" data-x-icon-s=\"&#xf105;\"><\/i><\/span><span class=\"x-acc-header-text\"><div>\u00bfC\u00f3mo les elijo como proveedor de asistencia?<\/div><\/span><\/span><\/button><div id=\"panel-e58-e8\" role=\"region\" aria-hidden=\"true\" aria-labelledby=\"tab-e58-e8\" data-x-toggleable=\"e58-e8\" data-x-toggle-collapse=\"1\" class=\"x-collapsed\"><div class=\"x-acc-content\"><div class=\"wpb_text_column wpb_content_element cr-animate-gen animation-done\" data-animate-type=\"transition.fadeIn\">\n<div class=\"wpb_wrapper\">\n<p><span>Elegir una empresa de asistencia es una decisi\u00f3n importante. Si est\u00e1 interesado en lo que podemos ofrecerle, p\u00f3ngase en contacto con nosotros y estaremos encantados de ir a su casa para contarle m\u00e1s cosas sobre nuestra empresa de asistencia y c\u00f3mo trabajamos. <\/span><\/p>\n<p><span>Una vez que haya decidido depositar su confianza en nosotros, redactaremos un contrato basado en lo que hayamos acordado. Tambi\u00e9n notificamos a la Seguridad Social y a su ayuntamiento que su prestaci\u00f3n de asistencia nos ser\u00e1 abonada. Acordaremos juntos cu\u00e1ndo comenzar\u00e1 su asistencia personal bajo nuestros auspicios.<\/span><\/p>\n<p><\/p>\n\n<\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"x-acc e58-e9 m1m-l m1m-n\" id=\"x-acc-e58-e9\"><div class=\"e58-e10 x-acc-item\"><button id=\"tab-e58-e10\" class=\"x-acc-header\" role=\"button\" aria-expanded=\"false\" aria-controls=\"panel-e58-e10\" data-x-toggle=\"collapse\" data-x-toggleable=\"e58-e10\" type=\"button\"><span class=\"x-acc-header-content\"><span class=\"x-acc-header-indicator\"><i class=\"x-icon\" aria-hidden=\"true\" data-x-icon-s=\"&#xf105;\"><\/i><\/span><span class=\"x-acc-header-text\">\u00bfCu\u00e1ndo podemos empezar la asistencia?<\/span><\/span><\/button><div id=\"panel-e58-e10\" role=\"region\" aria-hidden=\"true\" aria-labelledby=\"tab-e58-e10\" data-x-toggleable=\"e58-e10\" data-x-toggle-collapse=\"1\" class=\"x-collapsed\"><div class=\"x-acc-content\"><p><span>Depende un poco de c\u00f3mo le vaya hoy con el plazo de preaviso en su actual empresa de asistencia. Si ya tiene un grupo de asistentes que quiere trabajar con nosotros, podemos empezar de inmediato. <\/span><\/p>\n<p><span>Si necesita contratar asistentes, normalmente podemos empezar su asistencia en 2 semanas. Somos un empleador popular con baja rotaci\u00f3n de personal y ya hemos reunido asistentes interesados en toda Suecia en nuestro banco de candidatos.<\/span><\/p><\/div><\/div><\/div><\/div><div class=\"x-acc e58-e11 m1m-l m1m-n\" id=\"x-acc-e58-e11\"><div class=\"e58-e12 x-acc-item\"><button id=\"tab-e58-e12\" class=\"x-acc-header\" role=\"button\" aria-expanded=\"false\" aria-controls=\"panel-e58-e12\" data-x-toggle=\"collapse\" data-x-toggleable=\"e58-e12\" type=\"button\"><span class=\"x-acc-header-content\"><span class=\"x-acc-header-indicator\"><i class=\"x-icon\" aria-hidden=\"true\" data-x-icon-s=\"&#xf105;\"><\/i><\/span><span class=\"x-acc-header-text\">\u00bfC\u00f3mo se cambia de proveedor de asistencia?<\/span><\/span><\/button><div id=\"panel-e58-e12\" role=\"region\" aria-hidden=\"true\" aria-labelledby=\"tab-e58-e12\" data-x-toggleable=\"e58-e12\" data-x-toggle-collapse=\"1\" class=\"x-collapsed\"><div class=\"x-acc-content\"><p><span>Cuando firmamos un contrato, organizamos una reuni\u00f3n con los asistentes personales que desea que se unan a nosotros. Recibir\u00e1n informaci\u00f3n sobre nosotros y una oferta de empleo, y es posible que tambi\u00e9n se inicie un proceso de contrataci\u00f3n. <\/span><\/p>\n<p><span>Debe rescindir el contrato con su actual compa\u00f1\u00eda de asistencia. <\/span><span>Le ayudamos con el proceso de cancelaci\u00f3n. Durante el tiempo que transcurre hasta que su asistencia comienza con nosotros, mantenemos un estrecho contacto en el que planificamos juntos la realizaci\u00f3n de su asistencia. Tambi\u00e9n nos encargamos de la formaci\u00f3n de sus asistentes. Si lo desea, podemos encargarnos de todos los aspectos pr\u00e1cticos de la indemnizaci\u00f3n por asistencia, etc. con su antigua empresa de asistencia.<\/span><\/p>\n<p><\/p><\/div><\/div><\/div><\/div><div class=\"x-div e58-e13 m1m-o m1m-p m1m-q\"><\/div><\/div><\/div><\/div><\/div><div class=\"x-section e58-e14 m1m-0 m1m-2\"><div class=\"x-row x-container max width e58-e15 m1m-6 m1m-8 m1m-a\"><div class=\"x-row-inner\"><div class=\"x-col e58-e16 m1m-b m1m-d\"><div class=\"x-bg\" aria-hidden=\"true\"><div class=\"x-bg-layer-lower-image\"><\/div><\/div><div class=\"x-text x-text-headline e58-e17 m1m-f m1m-g m1m-j m1m-3 x-effect-exit\" data-x-effect=\"{&quot;scroll&quot;:true,&quot;offsetTop&quot;:&quot;10%&quot;,&quot;offsetBottom&quot;:&quot;10%&quot;,&quot;behaviorScroll&quot;:&quot;fire-once&quot;}\"><div class=\"x-text-content\"><div class=\"x-text-content-text\"><h2 class=\"x-text-content-text-primary\">Ninguno <br>\nplazo de preaviso<\/h2>\n<\/div><\/div><\/div><div class=\"x-div e58-e18 m1m-p m1m-q m1m-r\"><\/div><\/div><div class=\"x-col e58-e19 m1m-b m1m-e\"><div class=\"x-div x-hide-md x-hide-sm x-hide-xs e58-e20 m1m-q m1m-s\"><\/div><div class=\"x-text x-text-headline e58-e21 m1m-f m1m-k m1m-3 m1m-5 x-effect-exit\" data-x-effect=\"{&quot;scroll&quot;:true,&quot;offsetTop&quot;:&quot;10%&quot;,&quot;offsetBottom&quot;:&quot;10%&quot;,&quot;behaviorScroll&quot;:&quot;fire-once&quot;}\"><div class=\"x-text-content\"><div class=\"x-text-content-text\"><h4 class=\"x-text-content-text-primary\">En todos los sentidos, es tu asistencia personal y debe funcionar siempre. Por lo tanto, puede poner fin a nuestra misi\u00f3n cuando quiera, de un d\u00eda para otro si lo desea, porque siempre debe tener la oportunidad de decidir sobre su vida y su asistencia personal. Por otra parte, estamos seguros de que usted tambi\u00e9n estar\u00e1 m\u00e1s que satisfecho con la forma en que trabajamos con su asistencia personal\n<\/h4>\n<\/div><\/div><\/div><a class=\"x-anchor x-anchor-button e58-e22 m1m-t m1m-3 m1m-5 x-effect-exit\" tabindex=\"0\" href=\"#\" data-x-effect=\"{&quot;scroll&quot;:true,&quot;offsetTop&quot;:&quot;10%&quot;,&quot;offsetBottom&quot;:&quot;10%&quot;,&quot;behaviorScroll&quot;:&quot;fire-once&quot;}\"><div class=\"x-anchor-content\"><div class=\"x-anchor-text\"><span class=\"x-anchor-text-primary\">Seguir leyendo<\/span><\/div><\/div><\/a><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>C\u00f3mo elegir o cambiar de proveedor de asistencia \u00bfRecibe actualmente asistencia personal pero est\u00e1 pensando en cambiar de proveedor? \u00bfO est\u00e1 buscando ... <\/p>\n<div><a href=\"https:\/\/carelli.se\/es\/personligassistans\/byt-assistansbolag\/\" class=\"more-link\">Seguir leyendo<\/a><\/div>","protected":false},"author":1,"featured_media":0,"parent":39,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-blank-4.php","meta":{"footnotes":""},"class_list":["post-58","page","type-page","status-publish","hentry","no-post-thumbnail"],"_links":{"self":[{"href":"https:\/\/carelli.se\/es\/wp-json\/wp\/v2\/pages\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/carelli.se\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/carelli.se\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/carelli.se\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/carelli.se\/es\/wp-json\/wp\/v2\/comments?post=58"}],"version-history":[{"count":20,"href":"https:\/\/carelli.se\/es\/wp-json\/wp\/v2\/pages\/58\/revisions"}],"predecessor-version":[{"id":3015,"href":"https:\/\/carelli.se\/es\/wp-json\/wp\/v2\/pages\/58\/revisions\/3015"}],"up":[{"embeddable":true,"href":"https:\/\/carelli.se\/es\/wp-json\/wp\/v2\/pages\/39"}],"wp:attachment":[{"href":"https:\/\/carelli.se\/es\/wp-json\/wp\/v2\/media?parent=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}